{"id":8657,"date":"2010-05-05T10:36:05","date_gmt":"2010-05-05T13:36:05","guid":{"rendered":"http:\/\/www.walcordeiro.com.br\/v1\/?p=8657"},"modified":"2010-05-05T10:36:05","modified_gmt":"2010-05-05T13:36:05","slug":"vitoria-da-conquista-decretada-prisao-de-pms-envolvidos-em-chacina","status":"publish","type":"post","link":"https:\/\/www.walcordeiro.com.br\/v1\/2010\/05\/05\/vitoria-da-conquista-decretada-prisao-de-pms-envolvidos-em-chacina\/","title":{"rendered":"Vit\u00f3ria da Conquista: Decretada pris\u00e3o de PMs envolvidos em chacina"},"content":{"rendered":"<p>Acusados do assassinato de onze pessoas, em repres\u00e1lia \u00e0 morte do soldado PM Marcelo M\u00e1rcio Lima Silva, ocorrida em janeiro deste ano, dez policiais militares devem ser presos nesta quarta-feira,em Vit\u00f3ria da Conquista, a 509 km de Salvador. As pris\u00f5es foram autorizadas pelo juiz Reno Viana Soares, titular da Vara do Juri da comarca, a pedido do Minist\u00e9rio P\u00fablico. Tamb\u00e9m devem ser cumpridos mandados de busca e apreens\u00e3o na casa dos policiais. A Justi\u00e7a decretou a pris\u00e3o tempor\u00e1ria do tenente PM Arlande Ribeiro de Almeida e dos soldados Anderson Maciel Silva, Ronildo Vieira da Silva, Emerson Caires Novaes, Adailson Machado de Castro, Marcelo Carvalho Santos, Evandro Andrade Costa, Cristiano Meira Santos, Dilsolon Meira Santos, Handerson Menezes Santos. Os policiais s\u00e3o lotados no 9\u00ba Batalh\u00e3o de Pol\u00edcia Militar (BPM\/Vit\u00f3ria da Conquista) e na Companhia de A\u00e7\u00f5es Especiais do Sudoeste e Gerais (Caesg\/PM). <em>Informa\u00e7\u00f5es de A Tarde<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acusados do assassinato de onze pessoas, em repres\u00e1lia \u00e0 morte do soldado PM Marcelo M\u00e1rcio Lima Silva, ocorrida em janeiro deste ano, dez policiais militares devem ser presos nesta quarta-feira,em Vit\u00f3ria da Conquista, a 509 km de Salvador. As pris\u00f5es foram autorizadas pelo juiz Reno Viana Soares, titular da Vara do Juri da comarca, a pedido do Minist\u00e9rio P\u00fablico. Tamb\u00e9m devem ser cumpridos mandados de busca e apreens\u00e3o na casa dos policiais. A Justi\u00e7a decretou a pris\u00e3o tempor\u00e1ria do tenente PM Arlande Ribeiro de Almeida e dos soldados Anderson Maciel Silva, Ronildo Vieira da Silva, Emerson Caires Novaes, Adailson Machado&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[971,183,1336,343,609],"class_list":["post-8657","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-caesg","tag-conquista","tag-gaeco","tag-pm","tag-prisao"],"acf":[],"views":1490,"_links":{"self":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/8657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/comments?post=8657"}],"version-history":[{"count":2,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/8657\/revisions"}],"predecessor-version":[{"id":8659,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/8657\/revisions\/8659"}],"wp:attachment":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/media?parent=8657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/categories?post=8657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/tags?post=8657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}