{"id":55159,"date":"2014-01-23T08:17:37","date_gmt":"2014-01-23T11:17:37","guid":{"rendered":"http:\/\/www.walcordeiro.com.br\/v1\/?p=55159"},"modified":"2014-01-23T08:17:37","modified_gmt":"2014-01-23T11:17:37","slug":"a-mao-de-deus-no-salvou-diz-avo-de-crianca-que-carro-passou-por-cima","status":"publish","type":"post","link":"https:\/\/www.walcordeiro.com.br\/v1\/2014\/01\/23\/a-mao-de-deus-no-salvou-diz-avo-de-crianca-que-carro-passou-por-cima\/","title":{"rendered":"\u2018A m\u00e3o de Deus no salvou\u2019, diz av\u00f3 de crian\u00e7a que carro passou por cima"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"Crian\u00e7a estava com a av\u00f3, que tamb\u00e9m foi atingida. Encaminhados para unidade de sa\u00fade, eles j\u00e1 receberam alta m\u00e9dica\" src=\"http:\/\/www.verdadegospel.com\/adwp02\/content\/uploads\/2014\/01\/acidente_Reprodu%C3%A7%C3%A3o-TV-Anhanguera.jpg\" width=\"290\" height=\"196\" \/><\/p>\n<p>Crian\u00e7a estava com a av\u00f3, que tamb\u00e9m foi atingida. Carro passou duas vezes com a roda sobre o menino<\/p>\n<p>C\u00e2meras de seguran\u00e7a registraram o momento em que um menino de 5 anos e a av\u00f3, de 56, foram atropelados por um carro, na ter\u00e7a-feira (21), em An\u00e1polis, a 55 km de Goi\u00e2nia. Duas rodas do VW Gol passam sobre a crian\u00e7a, que se levanta e, caminhando, vai ajudar a mulher.<\/p>\n<p>Encaminhados ao Hospital de Urg\u00eancias de An\u00e1polis (Huana), as v\u00edtimas passaram por duas s\u00e9ries de exames. Segundo a unidade, ambos tiveram apenas escoria\u00e7\u00f5es leves. O menino recebeu alta m\u00e9dica na noite do mesmo dia. J\u00e1 a av\u00f3 foi liberada \u00e0s 11h desta quarta-feira (22).<\/p>\n<p>O atropelamento foi causado por outro acidente, que tamb\u00e9m \u00e9 flagrado pelas imagens. Em um cruzamento, um Honda Fit bate em um Chevrolet Celta e, em seguida, colide com o VW Gol, que estava estacionado. Com o impacto da colis\u00e3o, o carro atingido atropelou a idosa e o neto.<\/p>\n<p>A dupla caminhava pela rua e, ao ver que o VW Gol foi atingido, tentou subir para a cal\u00e7ada. No entanto, eles n\u00e3o foram r\u00e1pidos o suficiente e foram atropelados. Pessoas que passavam pela rua ajudaram as v\u00edtimas.<\/p>\n<p><strong>Relato<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Vilma e Jo\u00e3o Pedro passam bem ap\u00f3s acidente e j\u00e1 est\u00e3o em casa\" src=\"http:\/\/www.verdadegospel.com\/adwp02\/content\/uploads\/2014\/01\/atropelados-anapolis-Reprodu%C3%A7%C3%A3o-TV-Anhanguera.jpg\" width=\"290\" height=\"207\" \/><\/p>\n<p>Vilma e Jo\u00e3o Pedro passam bem ap\u00f3s acidente e j\u00e1 est\u00e3o em casa<\/p>\n<p>O menino Jo\u00e3o Pedro Nascimento, 5 anos, afirma que se levantou r\u00e1pido ap\u00f3s ser atropelado por estar muito preocupado com a av\u00f3, a dona de casa Vilma Theodoro do Nascimento, 56 anos, tamb\u00e9m atingida no acidente.<\/p>\n<p>A av\u00f3 disse que os dois \u201cnasceram de novo\u201d. \u201cFoi um milagre. Tenho certeza que a m\u00e3o de Deus nos pegou e salvou\u201d, afirmou em entrevista ao G1. Ela e o neto j\u00e1 est\u00e3o em casa e, segundo Vilma, o menino brinca com os amigos. \u201cMeu netinho est\u00e1 todo feliz com os paparicos que est\u00e1 recebendo. Nem parece que ele foi atropelado\u201d, relata a dona de casa.<!--more--><\/p>\n<p><strong>Sinaliza\u00e7\u00e3o<\/strong><\/p>\n<p>Os motoristas que se envolveram no acidente reclamam da falta de sinaliza\u00e7\u00e3o do local. Segundo o condutor do Celta, o Honda Fit trafegava em alta velocidade. \u201cEstava correndo muito. Acho que se ele estive de 40 km\/h, dava para ele ter parado\u201d, afirma o representante comercial Jo\u00e3o Birajara Camargo.<\/p>\n<p>O motorista que teria causado o acidente nega que trafegava em alta velocidade. \u201cNa hora, n\u00e3o prestei aten\u00e7\u00e3o, mas acredito que n\u00e3o estava correndo\u201d, justificou o representante comercial Henrique Ara\u00fajo.<\/p>\n<p>A Secretaria de Tr\u00e2nsito de An\u00e1polis informou que vai sinalizar o trecho at\u00e9 o final da semana.<\/p>\n<p><span style=\"line-height: 1.5em;\">Fonte:\u00a0<\/span><em style=\"line-height: 1.5em;\">G1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crian\u00e7a estava com a av\u00f3, que tamb\u00e9m foi atingida. Carro passou duas vezes com a roda sobre o menino C\u00e2meras de seguran\u00e7a registraram o momento em que um menino de 5 anos e a av\u00f3, de 56, foram atropelados por um carro, na ter\u00e7a-feira (21), em An\u00e1polis, a 55 km de Goi\u00e2nia. Duas rodas do VW Gol passam sobre a crian\u00e7a, que se levanta e, caminhando, vai ajudar a mulher. Encaminhados ao Hospital de Urg\u00eancias de An\u00e1polis (Huana), as v\u00edtimas passaram por duas s\u00e9ries de exames. Segundo a unidade, ambos tiveram apenas escoria\u00e7\u00f5es leves. O menino recebeu alta m\u00e9dica na&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"class_list":["post-55159","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"views":749,"_links":{"self":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/55159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/comments?post=55159"}],"version-history":[{"count":1,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/55159\/revisions"}],"predecessor-version":[{"id":55160,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/55159\/revisions\/55160"}],"wp:attachment":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/media?parent=55159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/categories?post=55159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/tags?post=55159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}