{"id":48391,"date":"2013-01-30T07:33:21","date_gmt":"2013-01-30T10:33:21","guid":{"rendered":"http:\/\/www.walcordeiro.com.br\/v1\/?p=48391"},"modified":"2013-01-30T07:33:21","modified_gmt":"2013-01-30T10:33:21","slug":"estudante-salvou-ao-menos-14-pessoas-antes-de-morrer-em-incendio","status":"publish","type":"post","link":"https:\/\/www.walcordeiro.com.br\/v1\/2013\/01\/30\/estudante-salvou-ao-menos-14-pessoas-antes-de-morrer-em-incendio\/","title":{"rendered":"Estudante salvou ao menos 14 pessoas antes de morrer em inc\u00eandio"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong><em>G1<\/em><\/strong><\/p>\n<p>Parentes e amigos do estudante de educa\u00e7\u00e3o f\u00edsica Vin\u00edcius Montardo Rosado, de 26 anos, tentam, com muito esfor\u00e7o, cumprir o que acreditam seja um dos \u00faltimos desejos do jovem e n\u00e3o chorar. O brincalh\u00e3o de quase dois metros, que nunca ficava emburrado, segundo sua fam\u00edlia, foi um dos 235 mortos no inc\u00eandio na boate Kiss, em\u00a0<a href=\"http:\/\/g1.globo.com\/rs\/rio-grande-do-sul\/cidade\/santa-maria.html\">Santa Maria<\/a>,\u00a0<a href=\"http:\/\/g1.globo.com\/topico\/rio-grande-do-sul.html\">Rio Grande do Sul<\/a>. Ele foi um dos primeiros a sair da casa noturna em chamas, mas decidiu voltar e ajudar quem n\u00e3o conseguia escapar. Pelo menos 14 pessoas foram retiradas daquele lugar pelo rapaz, segundo relatos de sobreviventes.<\/p>\n<div><img loading=\"lazy\" decoding=\"async\" title=\"Vinicius faz gesto que era considerado sua marca registrada (Foto: Reprodu\u00e7\u00e3o\/Arquivo Pessoal)\" src=\"http:\/\/s2.glbimg.com\/22YmdibVpCW2So0NNGBe7PJd7a-j1OcWVvIsZ2V-nBe0D5Pj9Ucm4Oww99p1LEIo\/s.glbimg.com\/jo\/g1\/f\/original\/2013\/01\/29\/vinicius-1.jpg\" alt=\"Vinicius faz gesto que era considerado sua marca registrada (Foto: Reprodu\u00e7\u00e3o\/Arquivo Pessoal)\" width=\"300\" height=\"225\" \/><\/div>\n<div><strong>Vin\u00edcius faz gesto que era considerado sua marca<br \/>\nregistrada (Foto: Reprodu\u00e7\u00e3o\/Arquivo Pessoal)<\/strong><\/div>\n<p>O\u00a0<strong>G1<\/strong>\u00a0esteve na casa onde o jovem vivia com a fam\u00edlia, em Santa Maria, nesta ter\u00e7a-feira (29). Logo na entrada da casa simples, alguns parentes que foram prestar condol\u00eancias \u00e0 fam\u00edlia estavam sentados em cadeiras de armar. Enquanto conversavam, tomavam chimarr\u00e3o.<\/p>\n<p>No quarto, a auxiliar de escrit\u00f3rio J\u00e9ssica Montardo Rosado, de 24 anos, irm\u00e3 de Vin\u00edcius, mostrou fotos dele ainda crian\u00e7a que tinham sido publicadas no Facebook. &#8220;A gente era muito unido. Sempre dormimos na mesma cama, desde pequenos&#8221;, disse.<\/p>\n<p>Ao abrir o guarda-roupas, ela retirou do canto da prateleira mais alta uma camisa do Internacional. &#8220;Aqui est\u00e1 tudo que ele tinha. Essa era a paix\u00e3o dele&#8221;, afirmou.<!--more--><\/p>\n<p>\u201cSe ele e muitos outros jovens n\u00e3o tivessem voltado para ajudar, essa trag\u00e9dia seria muito maior. Em vez de 234, seriam 400, 500 mortos\u201d, disse o pai de Vin\u00edcius, o gerente de eventos Ogier de Vargas Rosado, de 51 anos.<\/p>\n<p>O estudante estava animado com o futuro. Com formatura marcada para este ano, planejava seguir para S\u00e3o Paulo, onde trabalharia e juntaria um dinheiro para um cruzeiro mar\u00edtimo. Adepto de esportes que exigem f\u00edsico desenvolvido, como r\u00fagbi, queria se tornar lutador de MMA.<\/p>\n<p>Ele e seu melhor amigo, o empres\u00e1rio Bruno Perin, de 25 anos, criaram quando adolescentes um estilo de vida intitulado \u201cfree life style\u201d. \u201c\u00c9 como um \u2018carpe diem\u2019, sobre aproveitar ao m\u00e1ximo a vida. E acho que ele conseguiu isso durante a vida\u201d, lembrou o jovem.<\/p>\n<div id=\"5376\"><\/div>\n<p>Parentes contam que Vinicius adorava festas, mas cancelava qualquer evento se um amigo precisasse de ajuda. \u201cEra um rapaz muito humilde. Nunca vi ningu\u00e9m falar que n\u00e3o gostava dele\u201d, disse o pai. \u201cBrincava que ele era como uma baleia: grande, forte e doce.\u201d<\/p>\n<p>Foi em uma festa, por\u00e9m, que a vida do jovem chegou ao fim. Segundo testemunhas, na madrugada de domingo Vinicius saiu da boate e procurou a irm\u00e3. Ao ver que J\u00e9ssica estava bem, voltou ao pr\u00e9dio em chamas, para resgatar quem n\u00e3o conseguia encontrar a sa\u00edda.<\/p>\n<p>Depois de alguns minutos, foi retirado por bombeiros desacordado. Ele morreu na ambul\u00e2ncia, a caminho do hospital. No vel\u00f3rio coletivo realizado no gin\u00e1sio esportivo da cidade, pessoas que sobreviveram e que participaram da cerim\u00f4nia reconheceram Vinicius. \u201cPassavam e diziam: \u2018lembro dele. Foi ele quem me salvou\u2019\u201d, afirmou Bruno. Por suas contas, foram 14 os resgatados pelo estudante de educa\u00e7\u00e3o f\u00edsica. \u201cSanta Maria n\u00e3o pode ser lembrada como uma terra onde aconteceu uma trag\u00e9dia, mas uma terra de her\u00f3is\u201d, completou.<\/p>\n<div><img loading=\"lazy\" decoding=\"async\" title=\"Desenho feito por amigos de Vinicius (Foto: Paulo Toledo Piza\/G1)\" src=\"http:\/\/s2.glbimg.com\/SI-JmUC_pzoGb4W9EFeYDKRxtblpZaMzipnLnHQl71J5mVZ5TgGbEwsuLIRUG5Zu\/s.glbimg.com\/jo\/g1\/f\/original\/2013\/01\/29\/desenho.jpg\" alt=\"Desenho feito por amigos de Vinicius (Foto: Paulo Toledo Piza\/G1)\" width=\"300\" height=\"225\" \/><strong>Desenho feito por amigos de Vinicius<br \/>\n(Foto: Paulo Toledo Piza\/G1)<\/strong><\/div>\n<p>Inicialmente revoltado com o desprendimento do filho que causou sua morte, Ogier reviu sua opini\u00e3o ap\u00f3s pensar e conversar com a filha. \u201cEla me disse que, mesmo que eu estivesse l\u00e1 e tentasse impedi-lo, ele me empurraria e entraria. Era a \u00edndole dele. Se ele n\u00e3o tivesse entrado, sei que se arrependeria de ter deixado todas aquelas pessoas morrerem.\u201d<\/p>\n<p>Emocionado com o exemplo do filho, o gerente de eventos espera que o mundo tenha outros tantos Vinicius. \u201cSe o mundo tivesse esse tipo de solidariedade uma vez a cada seis meses, ele seria um lugar melhor para se viver.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; G1 Parentes e amigos do estudante de educa\u00e7\u00e3o f\u00edsica Vin\u00edcius Montardo Rosado, de 26 anos, tentam, com muito esfor\u00e7o, cumprir o que acreditam seja um dos \u00faltimos desejos do jovem e n\u00e3o chorar. O brincalh\u00e3o de quase dois metros, que nunca ficava emburrado, segundo sua fam\u00edlia, foi um dos 235 mortos no inc\u00eandio na boate Kiss, em\u00a0Santa Maria,\u00a0Rio Grande do Sul. Ele foi um dos primeiros a sair da casa noturna em chamas, mas decidiu voltar e ajudar quem n\u00e3o conseguia escapar. Pelo menos 14 pessoas foram retiradas daquele lugar pelo rapaz, segundo relatos de sobreviventes. Vin\u00edcius faz gesto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"class_list":["post-48391","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"views":559,"_links":{"self":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/48391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/comments?post=48391"}],"version-history":[{"count":1,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/48391\/revisions"}],"predecessor-version":[{"id":48392,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/48391\/revisions\/48392"}],"wp:attachment":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/media?parent=48391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/categories?post=48391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/tags?post=48391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}