{"id":47731,"date":"2012-12-14T21:26:17","date_gmt":"2012-12-15T00:26:17","guid":{"rendered":"http:\/\/www.walcordeiro.com.br\/v1\/?p=47731"},"modified":"2012-12-14T21:26:17","modified_gmt":"2012-12-15T00:26:17","slug":"cristaos-se-mobilizam-em-oracao-no-egito-com-medo-de-nova-ditadura","status":"publish","type":"post","link":"https:\/\/www.walcordeiro.com.br\/v1\/2012\/12\/14\/cristaos-se-mobilizam-em-oracao-no-egito-com-medo-de-nova-ditadura\/","title":{"rendered":"Crist\u00e3os se mobilizam em ora\u00e7\u00e3o no Egito com medo de nova ditadura"},"content":{"rendered":"<p>&nbsp;<br \/>\n<a title=\"\" href=\"http:\/\/noticias.gospelprime.com.br\/cristaos-se-mobilizam-em-oracao-no-egito-com-medo-de-nova-ditadura\/\"><img decoding=\"async\" title=\"Crist\u00e3os se mobilizam em ora\u00e7\u00e3o no Egito com medo de nova ditadura\" src=\"http:\/\/noticias.gospelprime.com.br\/files\/2012\/12\/Oracao-Egito.jpg\" alt=\"Crist\u00e3os se mobilizam em ora\u00e7\u00e3o no Egito com medo de nova ditadura\" \/><\/a><\/p>\n<p>Crist\u00e3os se mobilizam em ora\u00e7\u00e3o no Egito com medo de nova ditadura<\/p>\n<p>Crist\u00e3os eg\u00edpcios est\u00e3o se mobilizando para fazer um grande evento de ora\u00e7\u00e3o em favor de seu pa\u00eds. Neste s\u00e1bado a popula\u00e7\u00e3o estar\u00e1 votando no referendo sobre as altera\u00e7\u00f5es da Constitui\u00e7\u00e3o que dever\u00e1 instalar uma nova ditadura do pa\u00eds.<\/p>\n<p>O presidente Mohamed Morsi est\u00e1 sendo alvo de diversos protestos desde que decretou uma lei que ampliava seus poderes, al\u00e9m de ter que revog\u00e1-la, Morsi tamb\u00e9m precisou suspender o aumento de impostos de produtos b\u00e1sicos.<\/p>\n<p>Os crist\u00e3os temem que com o novo decreto a persegui\u00e7\u00e3o religiosa volte a acontecer no pa\u00eds, mas este n\u00e3o ser\u00e1 o \u00fanico motivo de ora\u00e7\u00e3o. Durante a reuni\u00e3o na Igreja do Cairo Cave eles tamb\u00e9m pedir\u00e3o pela unidade das igrejas e pelo reavivamento espiritual do pa\u00eds.<\/p>\n<p><!--more-->Uma emissora de\u00a0<a title=\"\" href=\"http:\/\/tv.gospelprime.com.br\/\">TV<\/a>\u00a0ir\u00e1 fazer a cobertura desta mobiliza\u00e7\u00e3o, o diretor do canal, Farid Garas, chegou a declarar que a ora\u00e7\u00e3o \u201c\u00e9 a melhor coisa e s\u00f3 o que podemos fazer agora, entre tudo o que est\u00e1 acontecendo\u201d.<\/p>\n<p>O executivo acredita que a uni\u00e3o dos crist\u00e3os vai alertar as autoridades do pa\u00eds. \u201cA igreja est\u00e1 encorajando todos os crist\u00e3os a fazer o seu dever nacional de assumir um papel na sociedade\u201d, disse.<\/p>\n<p>O referendo acontecer\u00e1 neste s\u00e1bado (15) e mais de 120 mil homens das For\u00e7as Armadas estar\u00e3o a postos para evitar confrontos.<\/p>\n<p>Gospel Prime<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Crist\u00e3os se mobilizam em ora\u00e7\u00e3o no Egito com medo de nova ditadura Crist\u00e3os eg\u00edpcios est\u00e3o se mobilizando para fazer um grande evento de ora\u00e7\u00e3o em favor de seu pa\u00eds. Neste s\u00e1bado a popula\u00e7\u00e3o estar\u00e1 votando no referendo sobre as altera\u00e7\u00f5es da Constitui\u00e7\u00e3o que dever\u00e1 instalar uma nova ditadura do pa\u00eds. O presidente Mohamed Morsi est\u00e1 sendo alvo de diversos protestos desde que decretou uma lei que ampliava seus poderes, al\u00e9m de ter que revog\u00e1-la, Morsi tamb\u00e9m precisou suspender o aumento de impostos de produtos b\u00e1sicos. Os crist\u00e3os temem que com o novo decreto a persegui\u00e7\u00e3o religiosa volte a acontecer&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"class_list":["post-47731","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"views":530,"_links":{"self":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/47731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/comments?post=47731"}],"version-history":[{"count":2,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/47731\/revisions"}],"predecessor-version":[{"id":47733,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/47731\/revisions\/47733"}],"wp:attachment":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/media?parent=47731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/categories?post=47731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/tags?post=47731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}