{"id":41632,"date":"2012-01-16T07:27:19","date_gmt":"2012-01-16T10:27:19","guid":{"rendered":"http:\/\/www.walcordeiro.com.br\/v1\/?p=41632"},"modified":"2012-01-16T07:27:19","modified_gmt":"2012-01-16T10:27:19","slug":"reforma-ministerial-nao-alcanca-militares-de-lula","status":"publish","type":"post","link":"https:\/\/www.walcordeiro.com.br\/v1\/2012\/01\/16\/reforma-ministerial-nao-alcanca-militares-de-lula\/","title":{"rendered":"Reforma ministerial n\u00e3o alcan\u00e7a militares de Lula"},"content":{"rendered":"<div>\n<div id=\"botoes\">\n<div><\/div>\n<\/div>\n<\/div>\n<div id=\"noticia\">\n<div><a title=\"Comandantes Enzo Peri (Ex\u00e9rcito), Juniti Saito (Aeron\u00e1utica) e Moura Neto (Marinha)\" href=\"http:\/\/i0.ig.com\/bancodeimagens\/6j\/dt\/0t\/6jdt0tuga23z1rymeohb0rasa.jpg\" rel=\"lightbox-foto\"><img decoding=\"async\" src=\"http:\/\/i0.ig.com\/bancodeimagens\/4g\/mh\/p0\/4gmhp0mdw3n8f81h18goq4hfo.jpg\" alt=\"\" \/><\/a><\/p>\n<div><cite>Foto: Ag\u00eancia Brasil<\/cite><a title=\"Comandantes Enzo Peri (Ex\u00e9rcito), Juniti Saito (Aeron\u00e1utica) e Moura Neto (Marinha)\" href=\"http:\/\/i0.ig.com\/bancodeimagens\/6j\/dt\/0t\/6jdt0tuga23z1rymeohb0rasa.jpg\" rel=\"lightbox-ampliar\">Ampliar<\/a><\/div>\n<div>\n<p>Comandantes Enzo Peri (Ex\u00e9rcito), Juniti Saito (Aeron\u00e1utica) e Moura Neto (Marinha)<\/p>\n<\/div>\n<\/div>\n<p>A reforma ministerial da presidenta Dilma Rousseff, planejada para fevereiro, n\u00e3o deve alcan\u00e7ar os comandantes das For\u00e7as Armadas. Heran\u00e7a do ex-presidente Luiz In\u00e1cio Lula da Silva, Enzo Peri (Ex\u00e9rcito), Juniti Saito (Aeron\u00e1utica) e Moura Neto (Marinha) v\u00e3o seguir no governo por pelo menos mais um ano.<\/p>\n<p>A avalia\u00e7\u00e3o de integrantes do governo \u00e9 que o processo de reestrutura\u00e7\u00e3o das For\u00e7as Armadas poderia ser interrompido no caso de mudan\u00e7as dos comandantes. No Planalto ainda h\u00e1 uma an\u00e1lise de que as For\u00e7as t\u00eam sido parceiras do governo. Dilma estaria satisfeita principalmente em rela\u00e7\u00e3o \u00e0s a\u00e7\u00f5es das For\u00e7as em situa\u00e7\u00f5es emerg\u00eancias de calamidade p\u00fablica, como no caso dos deslizamentos e enchentes.<!--more--><\/p>\n<p>Fora do governo e dentro dos muros dos quart\u00e9is a situa\u00e7\u00e3o tamb\u00e9m est\u00e1 positiva para Dilma. A reportagem conversou com militares da ativa que preferiram n\u00e3o se identificar. A maioria elogiou o governo da presidenta. Para eles, as For\u00e7as est\u00e3o com sua autonomia respeitada.<\/p>\n<p>Entre os reformados, tamb\u00e9m h\u00e1 um sentimento de paz com a presidente guerrilheira. \u201cN\u00e3o vimos nenhum sentimento de vingan\u00e7a. A anistia deixou tudo no zero a zero. Muitos militares votaram na Dilma. Pessoalmente vejo uma continuidade muito grande. Essa \u00e9 uma \u00e1rea que estava tranquila, n\u00e3o h\u00e1 porque fazer mudan\u00e7as\u201d, disse o vice-presidente do Clube Militar, general Clovis Bandeira. \u00daltimo Segundo<\/p>\n<p>Apesar da situa\u00e7\u00e3o de calmaria, o cen\u00e1rio futuro pode trazer turbul\u00eancias entre o governo e as For\u00e7as Armadas. Um dos desafios de Dilma vai ser a indica\u00e7\u00e3o dos membros da Comiss\u00e3o da Verdade.<\/p>\n<p>Parte da base governista, principalmente no PT, est\u00e1 ligada a ex-presos pol\u00edticos e torturados da ditadura. Para a cria\u00e7\u00e3o da Comiss\u00e3o foi necess\u00e1ria uma longa negocia\u00e7\u00e3o com as For\u00e7as. A indica\u00e7\u00e3o dos nomes pode gerar insatisfa\u00e7\u00f5es em ambos os lados.<\/p>\n<p>Outro problema est\u00e1 ligado diretamente \u00e0 reestrutura\u00e7\u00e3o das For\u00e7as Armadas. No Ex\u00e9rcito o ponto de tens\u00e3o est\u00e1 na renova\u00e7\u00e3o de programas de guerra, entre eles consta a compra de um novo sistema de m\u00edsseis terra-terra. As negocia\u00e7\u00f5es v\u00eam desde o governo Lula, quando o ministro da Defesa era Nelson Jobim. Aeron\u00e1utica, por sua vez, aguarda um desfecho para a compra de novos ca\u00e7as. A Marinha, por sua vez, pede recursos para a constru\u00e7\u00e3o do submarino movido a energia nuclear.<\/p>\n<p>Por fim, Dilma vai ter que lidar com os pedidos de aumento de sal\u00e1rios para os militares, tema que foi motivo de manifesta\u00e7\u00f5es no primeiro ano de governo da presidenta<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Ag\u00eancia BrasilAmpliar Comandantes Enzo Peri (Ex\u00e9rcito), Juniti Saito (Aeron\u00e1utica) e Moura Neto (Marinha) A reforma ministerial da presidenta Dilma Rousseff, planejada para fevereiro, n\u00e3o deve alcan\u00e7ar os comandantes das For\u00e7as Armadas. Heran\u00e7a do ex-presidente Luiz In\u00e1cio Lula da Silva, Enzo Peri (Ex\u00e9rcito), Juniti Saito (Aeron\u00e1utica) e Moura Neto (Marinha) v\u00e3o seguir no governo por pelo menos mais um ano. A avalia\u00e7\u00e3o de integrantes do governo \u00e9 que o processo de reestrutura\u00e7\u00e3o das For\u00e7as Armadas poderia ser interrompido no caso de mudan\u00e7as dos comandantes. No Planalto ainda h\u00e1 uma an\u00e1lise de que as For\u00e7as t\u00eam sido parceiras do governo. Dilma&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"class_list":["post-41632","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"views":532,"_links":{"self":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/41632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/comments?post=41632"}],"version-history":[{"count":1,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/41632\/revisions"}],"predecessor-version":[{"id":41633,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/41632\/revisions\/41633"}],"wp:attachment":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/media?parent=41632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/categories?post=41632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/tags?post=41632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}