{"id":21873,"date":"2010-10-28T07:48:15","date_gmt":"2010-10-28T10:48:15","guid":{"rendered":"http:\/\/www.walcordeiro.com.br\/v1\/?p=21873"},"modified":"2010-10-28T07:48:15","modified_gmt":"2010-10-28T10:48:15","slug":"decisao-do-ficha-lima-pode-mudar-eleitos-na-ba","status":"publish","type":"post","link":"https:\/\/www.walcordeiro.com.br\/v1\/2010\/10\/28\/decisao-do-ficha-lima-pode-mudar-eleitos-na-ba\/","title":{"rendered":"DECIS\u00c3O DO FICHA LIMA PODE MUDAR ELEITOS NA BA"},"content":{"rendered":"<p><em>Foto: Evil\u00e1rio J\u00fanior \/ BN<br \/>\n<\/em><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/bahianoticias.com.br\/fotos\/editor\/Image\/capitao_tadeu_sentado_alba_evilasiojr.jpg\" alt=\"\" width=\"350\" height=\"282\" \/><br \/>\n<em>Capit\u00e3o Tadeu pode\u00a0continuar na AL\u00a0<\/em><\/p>\n<p>Com a decis\u00e3o do Supremo Tribunal Federal (STF) em validar a Lei da Ficha Limpa para a elei\u00e7\u00e3o deste ano, na sess\u00e3o desta quarta-feira (27), pelo menos quatro parlamentares baianos eleitos em 3 de outubro podem perder o mandato: Carlos Brasileiro (PT), Maria Luiza Laudano (PTdoB), na Assembleia Legislativa da Bahia; e Geraldo Sim\u00f5es (PT) e J\u00e2nio Natal (PRP), na C\u00e2mara Federal. Como os votos dados a eles seriam considerados nulos, o c\u00e1lculo das coliga\u00e7\u00f5es seria alterado. Por conta disso, na AL, al\u00e9m de Carlos Brasileiro, Yulo Oiticica, tamb\u00e9m do PT, perderia a vaga, j\u00e1 que, sem os votos dos fichas sujas, a coliga\u00e7\u00e3o PT-PDT-PP e PRV perderia duas cadeiras. No lugar deles entrariam Capit\u00e3o Tadeu (PSB) e Wenceslau Augusto (PCdoB). No lugar de Maria Luiza Laudano, entraria Jurandy Oliveira (PRP). Em rela\u00e7\u00e3o \u00e0 C\u00e2mara Federal, no lugar de Geraldo Sim\u00f5es entraria o boxeador Acelino Pop\u00f3 Freitas (PRB), enquanto que a vaga de J\u00e2nio Natal ficaria com o Pastor Luciano (PMN). Atento \u00e0 vota\u00e7\u00e3o do TSE, J\u00e2nio Natal contesta a mudan\u00e7a e explica a sua situa\u00e7\u00e3o: \u201cEsclare\u00e7o que o nosso pedido de registro, j\u00e1 apreciado e deferido pelo TRE\/BA e pelo Plen\u00e1rio do TSE n\u00e3o tem nada a ver com a quest\u00e3o da Ficha Limpa. <!--more-->No nosso caso, o que se discute \u00e9 que a C\u00e2mara de Vereadores de Porto Seguro ainda n\u00e3o julgou as contas anuais de 2007 e 2008 e o candidato derrotado Uldurico Pinto, que \u00e9 o impugnante, tenta sustentar que a compet\u00eancia para o julgamento dessas contas \u00e9 o TCM\/BA. O TSE j\u00e1 disse, por in\u00fameras vezes nessas elei\u00e7\u00f5es, que mesmo com a Lei de Ficha Limpa quem deve julgar as contas anuais dos prefeitos \u00e9 o Poder Legislativo e como ainda n\u00e3o houve, em Porto Seguro, esse julgamento, n\u00e3o posso ser considerado ineleg\u00edvel\u201d.<\/p>\n<p><strong>(Evandro Matos) Bahia Noticias<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Evil\u00e1rio J\u00fanior \/ BN Capit\u00e3o Tadeu pode\u00a0continuar na AL\u00a0 Com a decis\u00e3o do Supremo Tribunal Federal (STF) em validar a Lei da Ficha Limpa para a elei\u00e7\u00e3o deste ano, na sess\u00e3o desta quarta-feira (27), pelo menos quatro parlamentares baianos eleitos em 3 de outubro podem perder o mandato: Carlos Brasileiro (PT), Maria Luiza Laudano (PTdoB), na Assembleia Legislativa da Bahia; e Geraldo Sim\u00f5es (PT) e J\u00e2nio Natal (PRP), na C\u00e2mara Federal. Como os votos dados a eles seriam considerados nulos, o c\u00e1lculo das coliga\u00e7\u00f5es seria alterado. Por conta disso, na AL, al\u00e9m de Carlos Brasileiro, Yulo Oiticica, tamb\u00e9m do&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"class_list":["post-21873","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"views":468,"_links":{"self":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/21873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/comments?post=21873"}],"version-history":[{"count":1,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/21873\/revisions"}],"predecessor-version":[{"id":21874,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/posts\/21873\/revisions\/21874"}],"wp:attachment":[{"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/media?parent=21873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/categories?post=21873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.walcordeiro.com.br\/v1\/wp-json\/wp\/v2\/tags?post=21873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}